{"id":24659,"count":1,"description":"Passez au niveau sup\u00e9rieur de la calibration automobile. Cette formation de r\u00e9glage avanc\u00e9e s'adresse aux professionnels cherchant \u00e0 ma\u00eetriser les modifications complexes. En int\u00e9grant des modules techniques comme la formation winols, nous vous aidons \u00e0 d\u00e9coder les secrets des calculateurs les plus r\u00e9cents. Que vous visiez des r\u00e9glages de Stage 2 ou 3, apprenez la reprogrammation moteur avanc\u00e9 avec les meilleurs outils du march\u00e9 pour garantir des r\u00e9sultats exceptionnels et fiables.","link":"https:\/\/remap-staging.24livehost.com\/fr\/categorie-produit\/formation-au-tuning-par-niveau\/avancee\/","name":"Formation de r\u00e9glage avanc\u00e9e","slug":"avancee","taxonomy":"product_cat","parent":24509,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/product_cat\/24659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/product_cat\/24509"}],"wp:post_type":[{"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/product?product_cat=24659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}