{"id":22072,"date":"2012-01-07T17:16:13","date_gmt":"2012-01-07T17:16:13","guid":{"rendered":"https:\/\/remap-staging.24livehost.com\/viezu-et-lequipe-de-lacademie-renforces-pour-2012\/"},"modified":"2025-12-08T08:03:12","modified_gmt":"2025-12-08T08:03:12","slug":"viezu-et-lequipe-de-lacademie-renforces-pour-2012","status":"publish","type":"post","link":"https:\/\/remap-staging.24livehost.com\/fr\/viezu-et-lequipe-de-lacademie-renforces-pour-2012\/","title":{"rendered":"Viezu et l&rsquo;\u00e9quipe de l&rsquo;Acad\u00e9mie renforc\u00e9s pour 2012"},"content":{"rendered":"<h2>Viezu et l&rsquo;\u00e9quipe de l&rsquo;Acad\u00e9mie renforc\u00e9s<\/h2>\n<p>Alors que nous entamons la nouvelle ann\u00e9e, une ann\u00e9e qui continuera \u00e0 voir Viezu se d\u00e9velopper et l&rsquo;introduction d&rsquo;un certain nombre de nouveaux cours de formation et d&rsquo;\u00e9v\u00e9nements, nous aimerions annoncer officiellement la nomination de notre nouveau directeur g\u00e9n\u00e9ral, Alasdair Maclachlan.<br \/>\nAlasdair nous rejoint avec une riche exp\u00e9rience dans les domaines de la vente, du marketing et de l&rsquo;apr\u00e8s-vente, acquise tout au long de sa carri\u00e8re dans l&rsquo;industrie automobile. Alasdair sera responsable de la gestion quotidienne de Viezu, de la garantie d&rsquo;une assistance coh\u00e9rente et de premier ordre aux concessionnaires, de la formation au <a href=\"http:\/\/www.remap101.co.uk\/2016\/10\/07\/learning-new-ecu-remapping-skills-viezu\/\" target=\"_blank\" rel=\"noopener\">remappage de l&rsquo;ECU<\/a> et des cours de tuning automobile.<\/p>\n<p>L&rsquo;ann\u00e9e 2012 s&rsquo;annonce passionnante. Nous avons pr\u00e9vu un certain nombre de nouveaux \u00e9v\u00e9nements de formation, notamment des tourn\u00e9es de pr\u00e9sentation et des formations en Inde, aux \u00c9tats-Unis, \u00e0 Duba\u00ef et en Allemagne. Nous avons \u00e9galement une nouvelle gamme de Dynos et de routes roulantes de Mustang, un nouveau site web pour Viezu et l&rsquo;\u00e9cole de formation, trop de nouveaux produits, services et couvertures de v\u00e9hicules pour les \u00e9num\u00e9rer, et toute une s\u00e9rie de r\u00e9compenses pour lesquelles nous sommes nomin\u00e9s dans les mois \u00e0 venir. Sans oublier l&rsquo;accr\u00e9ditation ISO, c&rsquo;est tout bon !<\/p>\n<p>Veuillez vous joindre \u00e0 nous pour souhaiter la bienvenue \u00e0 Alasdair dans la famille Viezu.<\/p>\n<p>Pour le <a href=\"https:\/\/viezu.com\/diesel-tuning-ecu-remapping-and-dpf-delete\" target=\"_blank\" rel=\"noopener\">d\u00e9montage du DPF et les probl\u00e8mes li\u00e9s au DPF<\/a>, ou pour les formations, les cours et les cours de <a href=\"http:\/\/www.remap101.co.uk\/2016\/10\/07\/learning-new-ecu-remapping-skills-viezu\/\" target=\"_blank\" rel=\"noopener\">remappage de l&rsquo;ECU<\/a>, veuillez consulter le <a href=\"http:\/\/www.remap101.co.uk\/\" target=\"_blank\" rel=\"noopener\">site http:\/\/www.remap101.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viezu et l&rsquo;\u00e9quipe de l&rsquo;Acad\u00e9mie renforc\u00e9s Alors que nous entamons la nouvelle ann\u00e9e, une ann\u00e9e qui continuera \u00e0 voir Viezu se d\u00e9velopper et l&rsquo;introduction d&rsquo;un certain nombre de nouveaux cours de formation et d&rsquo;\u00e9v\u00e9nements, nous aimerions annoncer officiellement la nomination de notre nouveau directeur g\u00e9n\u00e9ral, Alasdair Maclachlan. Alasdair nous rejoint avec une riche exp\u00e9rience dans [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1977],"tags":[6153,6008,6004,2841,2955,2873,2473,2843,2477,6023,2475,2994,6002,6009,6015,2952,4385,6037,3551,6006,2949,6027,6035,6019,6000,6031,2485,2865,2487,6021,6025,5544,6029,6033,6013,4509,2887,4502,6152,4505,6011,2871,6017,6151,3766,5855],"class_list":["post-22072","post","type-post","status-publish","format-standard","hentry","category-non-classifiee","tag-alasdair-maclachlan-fr","tag-apprendre-a-regler-les-voitures","tag-bleu-optimiser","tag-chiptuning-fr","tag-comment-regler-les-voitures-fr","tag-demontage-du-dpf","tag-equipement-de-tuning-pour-voiture","tag-formation-de-reprogrammation-de-lecu","tag-formation-tuning-voiture","tag-journee-de-dyno","tag-logiciel-de-reglage-de-voiture","tag-maitre-kess-fr","tag-meilleure-economie-de-carburant","tag-mustang-dyne-fr","tag-ou-regler-les-voitures","tag-outils-de-tuning-pour-voitures","tag-preparatifs-porsche","tag-reglage-au-royaume-uni","tag-reglage-audi","tag-reglage-bmw","tag-reglage-de-camion","tag-reglage-de-leconomie","tag-reglage-de-la-route-roulante","tag-reglage-de-la-technologie-extraterrestre","tag-reglage-de-la-voiture-cmd","tag-reglage-de-land-rover","tag-reglage-de-voiture","tag-reglage-diesel","tag-reglage-dimsport","tag-reglage-du-dpf","tag-reglage-du-jour-au-banc-dessai","tag-reglage-du-tracteur","tag-reglage-jaguar","tag-reglage-mercedes","tag-reglage-usa","tag-reglage-vw","tag-reprogrammation-de-lecu","tag-reprogrammation-de-lecu-audi","tag-reprogrammation-de-lecu-mobile","tag-reprogrammation-de-lecu-vw","tag-route-roulante-mustang","tag-suppression-dpf","tag-tuning-de-voiture-avec-technologie-alien","tag-tuning-de-voiture-mobile","tag-viezu-fr","tag-www-viezu-com-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/posts\/22072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/comments?post=22072"}],"version-history":[{"count":2,"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/posts\/22072\/revisions"}],"predecessor-version":[{"id":87299,"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/posts\/22072\/revisions\/87299"}],"wp:attachment":[{"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/media?parent=22072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/categories?post=22072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/remap-staging.24livehost.com\/fr\/wp-json\/wp\/v2\/tags?post=22072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}